{"id":5811,"date":"2024-01-15T07:32:26","date_gmt":"2024-01-15T06:32:26","guid":{"rendered":"https:\/\/avgs-gutschein.de\/nuestras-entrenadoras\/mandy-pursche\/"},"modified":"2024-10-17T11:58:08","modified_gmt":"2024-10-17T09:58:08","slug":"mandy-pursche","status":"publish","type":"page","link":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/","title":{"rendered":"Mandy Pursche"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbcoaches-img\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#e0e0e0&#8243; custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; use_custom_gutter=\u00bbon\u00bb make_equal=\u00bbon\u00bb _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/avgs-gutschein.de\/wp-content\/uploads\/2024\/01\/Mandy-Pursche_profile_img.webp\u00bb background_position=\u00bbtop_center\u00bb custom_padding_tablet=\u00bb38vw||38vw||true|false\u00bb custom_padding_phone=\u00bb38vw||38vw||true|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb3vw||3vw||true|false\u00bb custom_padding_tablet=\u00bb3vw||3vw||true|false\u00bb custom_padding_phone=\u00bb8vw||10vw||false|false\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|800|||||||\u00bb header_text_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Mandy Pursche<\/h1>\n<p>[\/et_pb_text][et_pb_text module_class=\u00bbsub-prof\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"coach-desc\">\n<p><strong>Producto:<\/strong> Coaching laboral, asesoramiento para la creaci\u00f3n de empresas<\/p>\n<hr \/>\n<p><strong>Idioma(s) del coaching: <\/strong>alem\u00e1n<\/p>\n<hr \/>\n<p><strong>Formaci\u00f3n\/certificaciones de coaching: <\/strong>t\u00edtulo de psic\u00f3logo\/coach personal, formaci\u00f3n en PNL, formaci\u00f3n de coaching wingwave, adem\u00e1s de varios seminarios avanzados con certificados, peque\u00f1o terapeuta alternativo<\/p>\n<hr \/>\n<p><strong>Experiencia en el sector: <\/strong>consultor\u00eda\/coaching, servicios, eventos\/ocio, comercio\/ventas, artesan\u00eda, marketing\/comunicaci\u00f3n<\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/#kontakt-mandy\u00bb button_text=\u00bbReserva una consulta inicial\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#cd222a\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#FFFFFF\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb make_equal=\u00bbon\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|3vw|||false|false\u00bb border_width_right=\u00bb1px\u00bb border_color_right=\u00bb#cd222a\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text module_class=\u00bbprof-question\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#cd222a\u00bb text_font_size=\u00bb24px\u00bb global_colors_info=\u00bb{}\u00bb]1. \u00bfQu\u00e9 dicen de ti tus clientes?[\/et_pb_text][et_pb_text module_class=\u00bbprof-answer\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb2em\u00bb link_text_color=\u00bb#cd222a\u00bb global_colors_info=\u00bb{}\u00bb]Con la Sra. Pursche est\u00e1s en muy buenas manos<\/p>\n<p>Con su trato s\u00faper agradable y amigable en un ambiente relajado y agradable, las preocupaciones sobre la b\u00fasqueda de empleo, las cartas de solicitud, etc., literalmente desaparecieron de mi mente.<\/p>\n<p>La Sra. Pursche me ayud\u00f3 mucho con su excelente competencia profesional y empat\u00eda.<\/p>\n<p>Su forma de trabajar tranquila, objetiva, comprensiva y maravillosamente flexible me quit\u00f3 los miedos y las dudas sobre las cartas de solicitud y las entrevistas de trabajo.<\/p>\n<p>Los ejercicios y las tareas me mostraron claramente mis puntos fuertes y desaparecieron muchos bloqueos.<\/p>\n<p>Siempre puedo contactar con la Sra. Pursche. Tambi\u00e9n me permite hacer llamadas telef\u00f3nicas a \u00faltima hora de la noche y concertar citas de \u00faltimo momento.<\/p>\n<p>\u00a1Con la Sra. Pursche voy en la direcci\u00f3n correcta![\/et_pb_text][et_pb_text module_class=\u00bbprof-question\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#cd222a\u00bb text_font_size=\u00bb24px\u00bb global_colors_info=\u00bb{}\u00bb]2. \u00bfQu\u00e9 te motiva y cu\u00e1l es tu tarea favorita como coach?[\/et_pb_text][et_pb_text module_class=\u00bbprof-answer\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#cd222a\u00bb global_colors_info=\u00bb{}\u00bb]Para m\u00ed, el coaching no es un trabajo, es mi pasi\u00f3n. Ver c\u00f3mo las creencias limitantes desaparecen en el aire o c\u00f3mo la incertidumbre se transforma r\u00e1pidamente en confianza me llena de alegr\u00eda. El desarrollo personal (reducir los miedos y el estr\u00e9s, resolver bloqueos y dudas sobre uno mismo, aumentar el rendimiento y la fuerza mental, cambiar las formas negativas de pensar y comportarse, desarrollar el potencial) es mi tarea favorita en el coaching.[\/et_pb_text][et_pb_text module_class=\u00bbprof-question\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#cd222a\u00bb text_font_size=\u00bb24px\u00bb global_colors_info=\u00bb{}\u00bb]3. \u00bfC\u00f3mo cambiar\u00e1 la digitalizaci\u00f3n el negocio del coaching en general? \u00bfY c\u00f3mo lo afrontar\u00e1s?[\/et_pb_text][et_pb_text module_class=\u00bbprof-answer\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb2em\u00bb global_colors_info=\u00bb{}\u00bb]Desde marzo de 2020, ofrezco coaching online adem\u00e1s del coaching presencial. Para ello utilizo Zoom. Por supuesto, siempre depende de las necesidades del cliente, porque no todos los m\u00e9todos se pueden implementar al 100% en el coaching online como en el coaching presencial. Tambi\u00e9n depende en gran medida de las preferencias del cliente. No todos los clientes se sienten c\u00f3modos con el coaching online y pueden preferir el coaching presencial respetando las normas de higiene. Seguramente habr\u00e1 cada vez m\u00e1s coaching online en el futuro, ya que tambi\u00e9n aporta muchas ventajas, como el ahorro de tiempo o la flexibilidad espacial. He realizado una formaci\u00f3n adicional como coach online de wingwave para ello. Porque creo que el coaching presencial no se puede trasladar simplemente al coaching online. Esto requiere que los coaches tengan competencias diferentes o m\u00e1s amplias. Algunos m\u00e9todos tambi\u00e9n deben adaptarse al coaching online.[\/et_pb_text][et_pb_text module_class=\u00bbprof-question\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#cd222a\u00bb text_font_size=\u00bb24px\u00bb global_colors_info=\u00bb{}\u00bb]4. \u00bfCu\u00e1l es la mejor manera de desconectar?[\/et_pb_text][et_pb_text module_class=\u00bbprof-answer\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#cd222a\u00bb global_colors_info=\u00bb{}\u00bb]De paseo con la familia y el perro.[\/et_pb_text][et_pb_text module_class=\u00bbprof-question\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#cd222a\u00bb text_font_size=\u00bb24px\u00bb global_colors_info=\u00bb{}\u00bb]5. \u00bfCu\u00e1les son las posibilidades del coaching individual y d\u00f3nde se alcanzan los l\u00edmites?[\/et_pb_text][et_pb_text module_class=\u00bbprof-answer\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#cd222a\u00bb global_colors_info=\u00bb{}\u00bb]El coaching es complejo y variado. El coaching individual significa que no trabajo con una caja de soluciones predefinidas, como suelen hacer los consultores, sino que abordo espec\u00edficamente las necesidades individuales de mis clientes. Todos somos diferentes y, por lo tanto, cada sesi\u00f3n de coaching es diferente y no todos los m\u00e9todos son adecuados para todos los clientes.<\/p>\n<p>El coaching se lleva a cabo de forma voluntaria y requiere una buena relaci\u00f3n de confianza entre el coach y el cliente. De lo contrario, aqu\u00ed se alcanzar\u00e1n r\u00e1pidamente los l\u00edmites.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbUbicaci\u00f3n \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe01d;||divi||400&#8243; icon_color=\u00bb#cd222a\u00bb image_icon_width=\u00bb40px\u00bb icon_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh2&#8243; body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb global_colors_info=\u00bb{}\u00bb]en l\u00ednea en toda Alemania Presencia en: Winsen (Luhe), Buchholz[\/et_pb_blurb][et_pb_blurb title=\u00bbFormaci\u00f3n profesional y experiencia profesional:\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf19d;||fa||900&#8243; icon_color=\u00bb#cd222a\u00bb image_icon_width=\u00bb40px\u00bb icon_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh2&#8243; header_line_height=\u00bb1.2em\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb global_colors_info=\u00bb{}\u00bb]Formaci\u00f3n de asistente legal, m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n, incluyendo selecci\u00f3n de personal, entrevistas de trabajo, etc. (sector de servicios financieros, sector ferial)[\/et_pb_blurb][et_pb_blurb title=\u00bbIntereses personales\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe030;||divi||400&#8243; icon_color=\u00bb#cd222a\u00bb image_icon_width=\u00bb40px\u00bb icon_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh2&#8243; header_line_height=\u00bb1.2em\u00bb body_font_size=\u00bb18px\u00bb body_line_height=\u00bb1.8em\u00bb global_colors_info=\u00bb{}\u00bb]Familia con perro y gato, acampada y naturaleza, atenci\u00f3n plena, bienes ra\u00edces[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00bbkontakt-mandy\u00bb _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb header_2_text_color=\u00bb#cd222a\u00bb header_2_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Solicitud de coaching de AVGS para Mandy Pursche<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb18px\u00bb text_line_height=\u00bb2em\u00bb global_colors_info=\u00bb{}\u00bb]Le enviaremos sus datos a Mandy Pursche para que pueda contactarte lo antes posible con una fecha sugerida para una consulta inicial sin compromiso. \u00bfQu\u00e9 solicitud de coaching de AVGS tienes?[\/et_pb_text][et_pb_code module_class=\u00bbcf-kntkt-form cf-sub-kntkt-form\u00bb _builder_version=\u00bb4.23.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5968-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"5968\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/5811#wpcf7-f5968-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"5968\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5968-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"what-can-we-do-for-you-answer\"><span class=\"wpcf7-form-control wpcf7-checkbox checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"what-can-we-do-for-you-answer[]\" value=\"Jobcoaching\" \/><span class=\"wpcf7-list-item-label\">Jobcoaching<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"what-can-we-do-for-you-answer[]\" value=\"Gr\u00fcndungsberatung\" \/><span class=\"wpcf7-list-item-label\">Gr\u00fcndungsberatung<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><label>Vor- und Nachname<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Vor-und-Nachname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Vor-und-Nachname\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><label>Telefonnummer<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefonnummer\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefonnummer\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"w3-col\">\n\t\t<p><label>E-Mail-Adresse<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><label>Mitteilung<\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"w3-col\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"mitteilung\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"max 500 Zeichen\" name=\"mitteilung\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><label>Wie haben Sie uns gefunden?<\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"how-did-you-find-us-answer\"><span class=\"wpcf7-form-control wpcf7-checkbox checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"how-did-you-find-us-answer[]\" value=\"Pers\u00f6nliche Empfehlung\" \/><span class=\"wpcf7-list-item-label\">Pers\u00f6nliche Empfehlung<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"how-did-you-find-us-answer[]\" value=\"Internetsuche\" \/><span class=\"wpcf7-list-item-label\">Internetsuche<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"how-did-you-find-us-answer[]\" value=\"Social Media\" \/><span class=\"wpcf7-list-item-label\">Social Media<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><label>Datenschutz<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"datenschutz\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"datenschutz[]\" value=\"Ich willige in die Verarbeitung meiner oben angegebenen personenbezogenen Daten zum Zwecke des Erhalts von Informationen zu Coachings ein. Meine Daten werden ggfls. zur Kontaktaufnahme an die zu vermittelten Coaches weitergegeben. Die weiteren Informationen zur Verarbeitung meiner Daten habe ich zur Kenntnis genommen. Ich bin mir bewusst, dass ich die erteilten Einwilligungen jederzeit telefonisch oder mit einer formlosen Mitteilung per E-Mail an kontakt@beratung-westphal.de widerrufen kann.\" \/><span class=\"wpcf7-list-item-label\">Ich willige in die Verarbeitung meiner oben angegebenen personenbezogenen Daten zum Zwecke des Erhalts von Informationen zu Coachings ein. Meine Daten werden ggfls. zur Kontaktaufnahme an die zu vermittelten Coaches weitergegeben. Die weiteren Informationen zur Verarbeitung meiner Daten habe ich zur Kenntnis genommen. Ich bin mir bewusst, dass ich die erteilten Einwilligungen jederzeit telefonisch oder mit einer formlosen Mitteilung per E-Mail an kontakt@beratung-westphal.de widerrufen kann.<\/span><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"w3-row\">\n\t<div class=\"w3-col\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-827\"><label><span class=\"wpcf7-quiz-label\">11 x 2 = ?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-827\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-827\" value=\"a165ff3442d955aabdac0dd4e20ac2b0\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<center>\n\t<div class=\"w3-row\">\n\t\t<div class=\"w3-col\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner pc-button bg-primary-color square-button primary-border-color\" type=\"submit\" value=\"Senden\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/center><div class=\"frc-captcha \" data-sitekey=\"FCMIVM5H8K1HPA6F\" data-lang=\"es\" ><\/div>\n\t\t<noscript>You need to enable Javascript for the anti-spam check.<\/noscript><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mandy Pursche Producto: Coaching laboral, asesoramiento para la creaci\u00f3n de empresas Idioma(s) del coaching: alem\u00e1n Formaci\u00f3n\/certificaciones de coaching: t\u00edtulo de psic\u00f3logo\/coach personal, formaci\u00f3n en PNL, formaci\u00f3n de coaching wingwave, adem\u00e1s de varios seminarios avanzados con certificados, peque\u00f1o terapeuta alternativo Experiencia en el sector: consultor\u00eda\/coaching, servicios, eventos\/ocio, comercio\/ventas, artesan\u00eda, marketing\/comunicaci\u00f3n 1. \u00bfQu\u00e9 dicen de ti tus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5247,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5811","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mandy Purche | Entrenamiento AVGS en Winsen, Buchholz y en l\u00ednea<\/title>\n<meta name=\"description\" content=\"Mandy Pursche ofrece coaching de AVGS con un enfoque en marketing, servicios, marketing y mucho m\u00e1s. Tambi\u00e9n tiene m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mandy Purche | Entrenamiento AVGS en Winsen, Buchholz y en l\u00ednea\" \/>\n<meta property=\"og:description\" content=\"Mandy Pursche ofrece coaching de AVGS con un enfoque en marketing, servicios, marketing y mucho m\u00e1s. Tambi\u00e9n tiene m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/\" \/>\n<meta property=\"og:site_name\" content=\"AVGS Gutschein\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T09:58:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/\",\"url\":\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/\",\"name\":\"Mandy Purche | Entrenamiento AVGS en Winsen, Buchholz y en l\u00ednea\",\"isPartOf\":{\"@id\":\"https:\/\/avgs-gutschein.de\/es\/#website\"},\"datePublished\":\"2024-01-15T06:32:26+00:00\",\"dateModified\":\"2024-10-17T09:58:08+00:00\",\"description\":\"Mandy Pursche ofrece coaching de AVGS con un enfoque en marketing, servicios, marketing y mucho m\u00e1s. Tambi\u00e9n tiene m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/avgs-gutschein.de\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestrxs entrenadorxs\",\"item\":\"https:\/\/avgs-gutschein.de\/es\/unsere-coaches\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mandy Pursche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/avgs-gutschein.de\/es\/#website\",\"url\":\"https:\/\/avgs-gutschein.de\/es\/\",\"name\":\"AVGS Gutschein\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/avgs-gutschein.de\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mandy Purche | Entrenamiento AVGS en Winsen, Buchholz y en l\u00ednea","description":"Mandy Pursche ofrece coaching de AVGS con un enfoque en marketing, servicios, marketing y mucho m\u00e1s. Tambi\u00e9n tiene m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/","og_locale":"es_ES","og_type":"article","og_title":"Mandy Purche | Entrenamiento AVGS en Winsen, Buchholz y en l\u00ednea","og_description":"Mandy Pursche ofrece coaching de AVGS con un enfoque en marketing, servicios, marketing y mucho m\u00e1s. Tambi\u00e9n tiene m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n.","og_url":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/","og_site_name":"AVGS Gutschein","article_modified_time":"2024-10-17T09:58:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/","url":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/","name":"Mandy Purche | Entrenamiento AVGS en Winsen, Buchholz y en l\u00ednea","isPartOf":{"@id":"https:\/\/avgs-gutschein.de\/es\/#website"},"datePublished":"2024-01-15T06:32:26+00:00","dateModified":"2024-10-17T09:58:08+00:00","description":"Mandy Pursche ofrece coaching de AVGS con un enfoque en marketing, servicios, marketing y mucho m\u00e1s. Tambi\u00e9n tiene m\u00e1s de 10 a\u00f1os de experiencia en gesti\u00f3n.","breadcrumb":{"@id":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avgs-gutschein.de\/es\/nuestrxs-entrenadorxs\/mandy-pursche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/avgs-gutschein.de\/es\/"},{"@type":"ListItem","position":2,"name":"Nuestrxs entrenadorxs","item":"https:\/\/avgs-gutschein.de\/es\/unsere-coaches\/"},{"@type":"ListItem","position":3,"name":"Mandy Pursche"}]},{"@type":"WebSite","@id":"https:\/\/avgs-gutschein.de\/es\/#website","url":"https:\/\/avgs-gutschein.de\/es\/","name":"AVGS Gutschein","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avgs-gutschein.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/pages\/5811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/comments?post=5811"}],"version-history":[{"count":5,"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/pages\/5811\/revisions"}],"predecessor-version":[{"id":7107,"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/pages\/5811\/revisions\/7107"}],"up":[{"embeddable":true,"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/pages\/5247"}],"wp:attachment":[{"href":"https:\/\/avgs-gutschein.de\/es\/wp-json\/wp\/v2\/media?parent=5811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}